{"id":26116,"date":"2023-12-04T13:57:23","date_gmt":"2023-12-04T12:57:23","guid":{"rendered":"https:\/\/campusfounders.de\/startups\/ai-start\/"},"modified":"2026-05-04T15:43:05","modified_gmt":"2026-05-04T13:43:05","slug":"ai-start","status":"publish","type":"page","link":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/","title":{"rendered":"AI Start"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26116\" class=\"elementor elementor-26116 elementor-26090\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-44d8d6a bg-mako cf-section cf-hero elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"44d8d6a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97419b7\" data-id=\"97419b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3add629 elementor-widget elementor-widget-html\" data-id=\"3add629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Meta Pixel Code -->\r\n<script>\r\n!function(f,b,e,v,n,t,s)\r\n{if(f.fbq)return;n=f.fbq=function(){n.callMethod?\r\nn.callMethod.apply(n,arguments):n.queue.push(arguments)};\r\nif(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\r\nn.queue=[];t=b.createElement(e);t.async=!0;\r\nt.src=v;s=b.getElementsByTagName(e)[0];\r\ns.parentNode.insertBefore(t,s)}(window, document,'script',\r\n'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\r\nfbq('init', '2079266535932983');\r\nfbq('track', 'PageView');\r\n<\/script>\r\n<noscript><img height=\"1\" width=\"1\" style=\"display:none\"\r\nsrc=\"https:\/\/www.facebook.com\/tr?id=2079266535932983&ev=PageView&noscript=1\"\r\n\/><\/noscript>\r\n<!-- End Meta Pixel Code -->\r\n\r\n<script src=\"https:\/\/consent.cookiefirst.com\/sites\/campusfounders.de-6514e894-b60e-4f3a-b7f4-2ff44a71a3e7\/consent.js\"><\/script>\r\n\r\n<script type=\"text\/javascript\">\r\n_linkedin_partner_id = \"5279713\";\r\nwindow._linkedin_data_partner_ids = window._linkedin_data_partner_ids || [];\r\nwindow._linkedin_data_partner_ids.push(_linkedin_partner_id);\r\n<\/script><script type=\"text\/javascript\">\r\n(function(l) {\r\nif (!l){window.lintrk = function(a,b){window.lintrk.q.push([a,b])};\r\nwindow.lintrk.q=[]}\r\nvar s = document.getElementsByTagName(\"script\")[0];\r\nvar b = document.createElement(\"script\");\r\nb.type = \"text\/javascript\";b.async = true;\r\nb.src = \"https:\/\/snap.licdn.com\/li.lms-analytics\/insight.min.js\";\r\ns.parentNode.insertBefore(b, s);})(window.lintrk);\r\n<\/script>\r\n<noscript>\r\n<img decoding=\"async\" height=\"1\" width=\"1\" style=\"display:none;\" alt=\"\" src=\"https:\/\/px.ads.linkedin.com\/collect\/?pid=5279713&fmt=gif\" \/>\r\n<\/noscript>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8462c34 nav-align-right elementor-widget elementor-widget-eael-one-page-nav\" data-id=\"8462c34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;heading_alignment&quot;:&quot;right&quot;}\" data-widget_type=\"eael-one-page-nav.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-one-page-nav-container\">\n            <ul class=\"eael-one-page-nav\" id=\"eael-one-page-nav-8462c34\" data-section-id=\"eael-one-page-nav-8462c34\" data-top-offset=\"80\" data-scroll-speed=\"900\" data-scroll-wheel=\"\" data-scroll-touch=\"\" data-scroll-keys=\"on\" data-section-ids=\"[&quot;overview&quot;,&quot;timeline&quot;,&quot;team&quot;,&quot;faq&quot;]\">\n                <li class=\"eael-one-page-nav-item\"><span class=\"eael-nav-dot-tooltip eael-tooltip-arrow\"><span class=\"eael-nav-dot-tooltip-content\">Programm\u00fcbersicht<\/span><\/span><a href=\"#\" aria-label=\"Programm\u00fcbersicht\" data-row-id=\"overview\"><span class=\"eael-nav-dot-wrap\"><i class=\"eael-nav-dot fas fa-circle\"><\/i><\/span><\/a><\/li><li class=\"eael-one-page-nav-item\"><span class=\"eael-nav-dot-tooltip eael-tooltip-arrow\"><span class=\"eael-nav-dot-tooltip-content\">Zeitleiste<\/span><\/span><a href=\"#\" aria-label=\"Zeitleiste\" data-row-id=\"timeline\"><span class=\"eael-nav-dot-wrap\"><i class=\"eael-nav-dot fas fa-circle\"><\/i><\/span><\/a><\/li><li class=\"eael-one-page-nav-item\"><span class=\"eael-nav-dot-tooltip eael-tooltip-arrow\"><span class=\"eael-nav-dot-tooltip-content\">Team<\/span><\/span><a href=\"#\" aria-label=\"Team\" data-row-id=\"team\"><span class=\"eael-nav-dot-wrap\"><i class=\"eael-nav-dot fas fa-circle\"><\/i><\/span><\/a><\/li><li class=\"eael-one-page-nav-item\"><span class=\"eael-nav-dot-tooltip eael-tooltip-arrow\"><span class=\"eael-nav-dot-tooltip-content\">FAQ<\/span><\/span><a href=\"#\" aria-label=\"FAQ\" data-row-id=\"faq\"><span class=\"eael-nav-dot-wrap\"><i class=\"eael-nav-dot fas fa-circle\"><\/i><\/span><\/a><\/li>            <\/ul>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3786b03 elementor-widget elementor-widget-cf-motto\" data-id=\"3786b03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cf-motto.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>hr.motto-seperator{width:115px!important; height:5px; border:0;  float:left;} <\/style>\n        <h2 class='motto-title' style='text-align:left'>\n        <hr class='motto-seperator' align=left\/>\n        <div style='clear:both'><span class='motto-accent'>AI START <br\/> <\/span>\n        <span class='motto-rest'> Starte deine KI-Gesch\u00e4ftsidee in nur 4 Wochen durch.<\/span>\n        <\/div>\n        <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0c2d5d elementor-align-right elementor-laptop-align-right elementor-mobile-align-left elementor-widget-laptop__width-auto sbtn btn-manatedark elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"a0c2d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/campusfounders.typeform.com\/to\/MeaTvM54\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Warteliste<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1aa3833 shadower w100 cf-section cf-summary elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1aa3833\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2111f5f\" data-id=\"2111f5f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6263f4b elementor-widget elementor-widget-heading\" data-id=\"6263f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wo angehende Gr\u00fcnder*innen modernste KI mit strategischem Gesch\u00e4ftssinn verbinden, um transformative Startups aufzubauen.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-926ec76 cf-section cf-anchor cf-desc cf-section-light-first elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"926ec76\" data-element_type=\"section\" data-e-type=\"section\" id=\"overview\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-703b9b7 cf-highlights\" data-id=\"703b9b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-489b891 elementor-widget elementor-widget-title-subtitle\" data-id=\"489b891\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class='cf-git'>\n            <div class='git-title' style='opacity: 0.7'><\/div>\n            <div class='git-seperator' style='height: 2px'><\/div>\n            <div class='git-name'>Programm\u00fcbersicht <b class=\"git-lastname\"><\/b><\/div>\n            <div class='git-greeting' style='opacity: 0.7'>\n                \n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1eae501 elementor-widget elementor-widget-text-editor\" data-id=\"1eae501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201eAI Start\u201c ist der Beginn Deiner Reise als KI-Startup-Gr\u00fcnder\/in. Der Kurs erm\u00f6glicht es Dir in nur vier Wochen Deine Startup-Idee durch die Entwicklung von KI-basierten Prototypen weiter zu entwickeln und zu validieren. Das Programm bringt Dir wesentliche Gesch\u00e4ftskomponenten n\u00e4her, wie Teambildung, Problemidentifizierung, Value Proposition, Pitching, MVP-Entwicklung, Grundlagen zu Gesch\u00e4ftsmodellen, Kapitalbeschaffung und rechtlichen \u00dcberlegungen. Dar\u00fcber hinaus bietet er spezielle Inhalte zu KI, einschlie\u00dflich deren Anwendung, Automatisierung, personalisierte KI-Modelle, Prototyping, Produktentwicklung und KI-getriebener Gesch\u00e4ftsmodelle.<br \/>Die Teilnahme am Programm ist kostenlos, erfordert jedoch eine Bewerbung.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-56433f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56433f0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2255e69\" data-id=\"2255e69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-706b954 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"706b954\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tZielgruppe\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDie Zielgruppe von \"AI Start\" sind angehende Gr\u00fcnder*innen, die ihre  Startup-Ideen entwickeln und  validieren wollen, indem sie k\u00fcnstliche  Intelligenz in ihre Prototypen integrieren.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0154458\" data-id=\"0154458\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df7c710 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"df7c710\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cog\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSETUP\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAI Start bietet ein strukturiertes Programm, um Startup-Ideen mit Schwerpunkt auf KI zu entwickeln und zu validieren. Es deckt alle wesentlichen Grundlagen ab und wird durch Mentoring und Experten unterst\u00fctzt.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-48b92e8\" data-id=\"48b92e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85f4605 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"85f4605\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tZIEL\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNach Abschluss des Programms haben die Teilnehmer*innen, das erforderliche Wissen und die F\u00e4higkeiten, um ihre Startup-Ideen effektiv zu entwickeln, zu validieren und mit der Umsetzung zu beginnen. Dabei liegt ein besonderer Schwerpunkt auf der Nutzung k\u00fcnstlicher Intelligenz.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-1956d9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1956d9d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d200ce\" data-id=\"0d200ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3562bac elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3562bac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDAUER\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<b>4 Wochen<\/b> vor Ort in Heilbronn\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca19dcf\" data-id=\"ca19dcf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4838cea elementor-widget elementor-widget-icon-box\" data-id=\"4838cea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOption auf direkte Weiterf\u00fchrung im Inkubator (6 Monate)\r\n\r\n\r\n\r\n\r\n\r\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9b99208 cf-section cf-anchor elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b99208\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d23127d\" data-id=\"d23127d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19247d0 elementor-widget elementor-widget-title-subtitle\" data-id=\"19247d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class='cf-git'>\n            <div class='git-title' style='opacity: 0.7'><\/div>\n            <div class='git-seperator' style='height: 2px'><\/div>\n            <div class='git-name'>PROGRAMM\u00dcBERSICHT <b class=\"git-lastname\"><\/b><\/div>\n            <div class='git-greeting' style='opacity: 0.7'>\n                \n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a620116 cf-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a620116\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df3f757\" data-id=\"df3f757\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-172a60b cf-highlights cf-highlights-first elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"172a60b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-160cc67\" data-id=\"160cc67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86df950 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"86df950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/12\/highlights2_aistart.jpg\" class=\"attachment-full size-full wp-image-26170\" alt=\"\" srcset=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/12\/highlights2_aistart.jpg 600w, https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/12\/highlights2_aistart-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ZUGANG ZU COACHING UND MENTOREN:<\/h3><p class=\"elementor-image-box-description\">Durch den Zugang zu Coaches und Mentoren w\u00e4hrend des Programms erhalten die Teilnehmer*innen wertvolle Betreuung, pers\u00f6nliche Einblicke und Branchenkenntnisse, die das Lernen, die Entwicklung von F\u00e4higkeiten und die strategische Entscheidungsfindung beschleunigen und so ihre Chancen erh\u00f6hen, die Herausforderungen der Startup-Entwicklung erfolgreich zu meistern und k\u00fcnstliche Intelligenz effektiv zu nutzen.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b025f elementor-position-right elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"68b025f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/07\/highlight_aif_3.jpg\" class=\"attachment-full size-full wp-image-25420\" alt=\"\" srcset=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/07\/highlight_aif_3.jpg 600w, https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/07\/highlight_aif_3-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"> ZUGANG ZU UNSEREM CAMPUS LAB SPACE<\/h3><p class=\"elementor-image-box-description\">W\u00e4hrend deiner Teilnahme an dem Programm hast du Zugang zu unseren verschiedenen Arbeitsr\u00e4umen. Du profitierst von moderner Ausstattung, einer lebendigen Gemeinschaft von Gleichgesinnten und einer g\u00fcnstigen Lage im Herzen der  Stadt Heilbronn - einem Hotspot f\u00fcr k\u00fcnstliche Intelligenz in Deutschland..<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccaaba4 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"ccaaba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/12\/highlights1_aistart.jpg\" class=\"attachment-full size-full wp-image-26168\" alt=\"\" srcset=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/12\/highlights1_aistart.jpg 600w, https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/12\/highlights1_aistart-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Eine aktive Community mit relevanten Akteuren, die deine Idee voranbringen<\/h3><p class=\"elementor-image-box-description\">Um erfolgreich zu sein, brauchen Startups und Innovatoren ein starkes Netzwerk. Aus diesem Grund fungieren wir als Bindeglied f\u00fcr das \u00d6kosystem. Talente, Unternehmer, regionale und internationale Startups, Investoren, Mentoren, Experten und Unternehmen beteiligen sich aktiv an unserer Community, sowohl physisch als auch online.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e37d12d elementor-position-right elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e37d12d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/07\/highlight_aif_2.jpg\" class=\"attachment-full size-full wp-image-25422\" alt=\"\" srcset=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/07\/highlight_aif_2.jpg 600w, https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/07\/highlight_aif_2-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">KOSTENLOSES CO-LIVING AUF H\u00d6CHSTEM NIVEAU<\/h3><p class=\"elementor-image-box-description\">Unsere atemberaubenden Apartments im Rosenberg Quartier sind f\u00fcr Dich und Dein Team da und bieten dir Komfort, Bequemlichkeit und ein inspirierendes Umfeld.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-db1e099 cf-section cf-timeline elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db1e099\" data-element_type=\"section\" data-e-type=\"section\" id=\"timeline\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-894d323\" data-id=\"894d323\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77d4ce4 elementor-widget elementor-widget-title-subtitle\" data-id=\"77d4ce4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class='cf-git'>\n            <div class='git-title' style='opacity: 0.7'><\/div>\n            <div class='git-seperator' style='height: 2px'><\/div>\n            <div class='git-name'>BEWERBUNGSPROZESS UND ZEITPLAN <b class=\"git-lastname\"><\/b><\/div>\n            <div class='git-greeting' style='opacity: 0.7'>\n                \n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ad4b72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ad4b72\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c30077b\" data-id=\"c30077b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-179cfd7 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"179cfd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9deef49 elementor-widget elementor-widget-text-editor\" data-id=\"9deef49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong class=\"fs-6\">Bewerbungsschluss<\/strong><\/p>\n<div>09.02.2026<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2bded34\" data-id=\"2bded34\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-586e1dd elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"586e1dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-605f9e2 elementor-widget elementor-widget-text-editor\" data-id=\"605f9e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>BENACHRICHTIGUNG \u00dcBER DIE ANNAHME<\/strong><br \/>13.02.2026<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-81ca7a8 elementor-widget elementor-widget-text-editor\" data-id=\"81ca7a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"TypographyPresentation TypographyPresentation--m RichText3-paragraph--withVSpacingNormal RichText3-paragraph\" style=\"text-align: center;\"><strong>4-Wochen-Programm\u00a0<\/strong><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec8e53f elementor-widget elementor-widget-eael-content-timeline\" data-id=\"ec8e53f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-content-timeline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"eael-content-timeline-ec8e53f\" class=\"content-timeline-layout-center date-position- horizontal-timeline-wrapper\" data-slide_to_scroll=\"{&quot;desktop&quot;:1,&quot;mobile&quot;:1,&quot;tablet&quot;:1,&quot;laptop&quot;:1}\">\n\t\t\t<div class=\"eael-content-timeline-container\">\n\t\t\t\t<div class=\"eael-content-timeline-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-content-timeline-block\">\n    <div class=\"eael-content-timeline-line\">\n        <div class=\"eael-content-timeline-inner\"><\/div>\n    <\/div>\n    <div class=\"eael-content-timeline-img eael-picture \"><\/div><div class=\"eael-content-timeline-content\"><span class=\"eael-date\">Woche 1: 02\/03 - 06\/03<\/span><div class=\"eael-timeline-excerpt\"><p><strong>Workshop 1:<\/strong> Die Auswahl eines initialen Marktes mit dem 'MON'<br \/><strong>Workshop 2:<\/strong> Den Endnutzer \/ Persona Profil und deren Probleme definieren<br \/><strong>Workshop 3:<\/strong> Das Werteversprechen definieren und quantifizieren<\/p>\n<\/div><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-content-timeline-block\">\n    <div class=\"eael-content-timeline-line\">\n        <div class=\"eael-content-timeline-inner\"><\/div>\n    <\/div>\n    <div class=\"eael-content-timeline-img eael-picture \"><\/div><div class=\"eael-content-timeline-content\"><span class=\"eael-date\">Woche 2: 09\/03 - 13\/03<\/span><div class=\"eael-timeline-excerpt\"><p><strong>Workshop 4:<\/strong> Den gesamten life cycle use case definieren<br \/><strong>Workshop 5:<\/strong> Die wichtigsten Annahmen identifizieren und testen (mit KI)<\/p>\n<\/div><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-content-timeline-block\">\n    <div class=\"eael-content-timeline-line\">\n        <div class=\"eael-content-timeline-inner\"><\/div>\n    <\/div>\n    <div class=\"eael-content-timeline-img eael-picture \"><\/div><div class=\"eael-content-timeline-content\"><span class=\"eael-date\">Woche 3: 16\/03 - 20\/03<\/span><div class=\"eael-timeline-excerpt\"><p><strong>Workshop 6:<\/strong> Den MVP definieren und entwickeln (mit KI)<br \/><strong>Workshop 7:<\/strong> Nutzertests durchf\u00fchren und Produktplan aufstellen<\/p>\n<\/div><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-content-timeline-block\">\n    <div class=\"eael-content-timeline-line\">\n        <div class=\"eael-content-timeline-inner\"><\/div>\n    <\/div>\n    <div class=\"eael-content-timeline-img eael-picture \"><\/div><div class=\"eael-content-timeline-content\"><span class=\"eael-date\">Woche 4: 23\/03 - 27\/03<\/span><div class=\"eael-timeline-excerpt\"><p><strong>Workshop 8:<\/strong> Wie du dein Start-Up Pitchst (mit Midjourney)<br \/><strong>AI Start Finale<\/strong><\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-cf612b2 cf-section cf-anchor elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf612b2\" data-element_type=\"section\" data-e-type=\"section\" id=\"team\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56e5936\" data-id=\"56e5936\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-a407a07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a407a07\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-087ec3f\" data-id=\"087ec3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83e5683 elementor-widget elementor-widget-title-subtitle\" data-id=\"83e5683\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class='cf-git'>\n            <div class='git-title' style='opacity: 0.7'><\/div>\n            <div class='git-seperator' style='height: 2px'><\/div>\n            <div class='git-name'>LERNE DAS TEAM KENNEN <b class=\"git-lastname\"><\/b><\/div>\n            <div class='git-greeting' style='opacity: 0.7'>\n                \n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-55293ca equal-height elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55293ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-79486d8\" data-id=\"79486d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c9c9a6 shadower btn-wattledark eael-team-align-eael-team-align-default elementor-widget elementor-widget-eael-team-member\" data-id=\"1c9c9a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t<div id=\"eael-team-member-1c9c9a6\" class=\"eael-team-item eael-team-members-centered \">\n\t\t<div class=\"eael-team-item-inner\">\n\t\t\t<div class=\"eael-team-image\">\n\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2025\/02\/team_marina.jpg\" alt=\"\">\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<div class=\"eael-team-content\">\n\t\t\t\t<h2 class=\"eael-team-member-name\">Marina Iantorno<\/h2><h3 class=\"eael-team-member-position\">AI Lead<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"eael-team-member-social-profiles\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"eael-team-member-social-link\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/marina-iantorno-752b6b133\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t<p class=\"eael-team-text\"><\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7b90779\" data-id=\"7b90779\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8d78f4a\" data-id=\"8d78f4a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c952a7e\" data-id=\"c952a7e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-14d3cf8 cf-section cf-anchor cf-desc cf-section-light-first cf-section-light-last elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14d3cf8\" data-element_type=\"section\" data-e-type=\"section\" id=\"faq\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c94178e\" data-id=\"c94178e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c562c23 elementor-widget elementor-widget-title-subtitle\" data-id=\"c562c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class='cf-git'>\n            <div class='git-title' style='opacity: 0.7'><\/div>\n            <div class='git-seperator' style='height: 2px'><\/div>\n            <div class='git-name'>FAQ <b class=\"git-lastname\"><\/b><\/div>\n            <div class='git-greeting' style='opacity: 0.7'>\n                \n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-34666e7 shadower btn-manate elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34666e7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-270a23a\" data-id=\"270a23a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87c63d2 elementor-widget elementor-widget-toggle\" data-id=\"87c63d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1421\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1421\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">WIE VIEL KOSTET DIE TEILNAHME?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1421\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1421\"><p>Die Teilnahme am Programm ist f\u00fcr unsere Teilnehmer kostenlos. Du musst lediglich durch eine Bewerbung in das Programm gelangen und uns von deiner Motivation \u00fcberzeugen.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1422\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1422\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">WER KANN SICH BEWERBEN?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1422\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1422\"><p>Jede Person, die die intrinsische Motivation mitbringt, kann sich bewerben. Ihr k\u00f6nnt euch auch als Team bewerben. Wir freuen uns auf Einzelpersonen und Teams, die eine hohe Motivation und Bereitschaft zeigen, den ersten Schritt ihrer Startup-Reise zu machen und eine anf\u00e4ngliche Validierung ihres Projekts m\u00f6chten.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1423\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1423\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">WIE WERDEN DIE TEILNEHMER AUSGEW\u00c4HLT?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1423\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1423\"><p>Wir w\u00e4hlen unsere Teilnehmer auf Grundlage ihres Teamsettings, des Validierungsstands und ihrer F\u00e4higkeiten aus. Auch deine Offenheit, sich einem anderen Team anzuschlie\u00dfen, spielt eine Rolle.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1424\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1424\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">WAS, WENN ICH NUR VIRTUELL TEILNEHMEN KANN?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1424\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1424\"><p>Die Workshops werden pers\u00f6nlich oder hybrid abgehalten, wenn die Nachfrage zu hoch ist. Wir betrachten die Workshop-Sitzungen jedoch als verbindlich f\u00fcr die Teilnehmer von AI Start. Neben den Workshops geht es um den Fortschritt deines Projekts. F\u00fcr deine private Arbeit an der Entwicklung ist es nicht zwingend erforderlich, die ganze Zeit pers\u00f6nlich anwesend zu sein.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1425\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1425\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">WAS IST DER INHALT DES PROGRAMMS?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1425\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1425\"><p>Das Ziel ist, eine anf\u00e4ngliche Validierung f\u00fcr dein Projekt zu erhalten. Daf\u00fcr werden Methoden aus Design Thinking und Lean Startup angewendet. Deine Motivation wird jedoch den Unterschied ausmachen und dir erm\u00f6glichen, ein Ergebnis zu erzielen, das echten Wert schafft.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1426\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1426\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">WELCHE SPRACHE WIRD IM PROGRAMM VERWENDET?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1426\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1426\"><p>Englisch. Nur so k\u00f6nnen wir die Vielfalt in Bezug auf Nationalit\u00e4t und demografischen Hintergrund sicherstellen. Wir erwarten, dass alle Teilnehmer grundlegendes Englisch sprechen und schreiben k\u00f6nnen &#8211; nicht perfekt, aber in der Lage sind, sich auszudr\u00fccken.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1427\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1427\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">ICH HABE EINE IDEE, ABER MEINE L\u00d6SUNG BEINHALTET KEINE KI. KANN ICH TROTZDEM BEWERBEN?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1427\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1427\"><p>Wir bewerten deine L\u00f6sung nach drei verschiedenen Levels, wie stark KI in deiner L\u00f6sung involviert ist. Da du auch mit der KI-Technologie vertrauter wirst, solltest du\u00a0 mindestens KI-Level 3 erreichen.<br \/>Die Level sind:<br \/>&#8211; Level 1: KI ist zentral f\u00fcr die Probleml\u00f6sung: &#8222;Das Wertversprechen (Value Proposition) wird durch KI erm\u00f6glicht&#8220;<br \/>&#8211; Level 2: Integrierter Bestandteil der Probleml\u00f6sung: &#8222;KI ist ein Teil der kundenorientierten Produktmerkmalen&#8220;<br \/>&#8211; Level 3: Unterst\u00fctzende Rolle in der Probleml\u00f6sung \/ im Gesch\u00e4ftsbereich<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1428\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1428\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was sind die 3 KI-Levels im Detail?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1428\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1428\"><p>Hier findest du\u00a0 weitere Informationen zu den 3 KI-Levels:<br \/>Level 1: KI ist zentral f\u00fcr die Probleml\u00f6sung: &#8222;Das Wertversprechen (Value Proposition) wird durch KI erm\u00f6glicht&#8220;<br \/>In diesem Szenario spielt KI eine zentrale und unverzichtbare Rolle in der L\u00f6sung deines Startups. Das gesamte Gesch\u00e4ftsmodell dreht sich um die F\u00e4higkeiten und Erkenntnisse, die durch k\u00fcnstliche Intelligenz bereitgestellt werden. Die Kernfunktionalit\u00e4t und das Wertversprechen des Startups beruhen stark auf KI-Algorithmen und Modellen. Diese Integrationsebene impliziert, dass dein Startup ohne KI seinen Wettbewerbsvorteil verlieren w\u00fcrde oder sogar vollkommen versagen k\u00f6nnte, seine Hauptdienstleistungen zu erbringen.<br \/>Beispiel: Ein Healthcare-Startup, das KI f\u00fcr personalisierte Medizin einsetzt, bei dem diagnostische und Behandlungsempfehlungen vollst\u00e4ndig von fortschrittlichen maschinellen Lernalgorithmen analysiert werden.<\/p>\n<p>Level 2: Integrierter Bestandteil der L\u00f6sung &#8222;KI ist Teil kundenorientierter Produktmerkmale&#8220;<br \/>Auf dieser Ebene ist KI ein integraler Bestandteil der L\u00f6sung des Startups und tr\u00e4gt wesentlich zur Effizienz und Effektivit\u00e4t bei. Obwohl nicht der alleinige Treiber, verbessert k\u00fcnstliche Intelligenz verschiedene Aspekte der Betriebsabl\u00e4ufe, Entscheidungsfindung oder Benutzererfahrung des Startups erheblich. Die L\u00f6sung k\u00f6nnte auch ohne KI existieren, aber ihre Leistung, Skalierbarkeit oder Benutzerzufriedenheit w\u00e4re beeintr\u00e4chtigt. KI fungiert als Multiplikator, der die Wirkung und F\u00e4higkeiten des Angebots des Startups verst\u00e4rkt.<br \/>Beispiel: Eine E-Commerce-Plattform, die KI f\u00fcr personalisierte Produktempfehlungen nutzt, um die Benutzerbindung zu verbessern und die Konversionsraten zu steigern.<\/p>\n<p>Level 3: Unterst\u00fctzende Rolle in der L\u00f6sung \/ im Gesch\u00e4ft<br \/>In diesem Szenario ist KI ein unterst\u00fctzendes Werkzeug, das bestimmte Funktionen im Startup unterst\u00fctzt. Die L\u00f6sung kann ohne KI recht gut funktionieren, aber k\u00fcnstliche Intelligenz wird eingesetzt, um bestimmte Aufgaben zu optimieren, Prozesse zu rationalisieren oder zus\u00e4tzliche Einblicke zu bieten. Es verbessert die Effizienz und Produktivit\u00e4t, ver\u00e4ndert jedoch nicht grundlegend die Natur des Produkts oder der Dienstleistung des Startups. Das Startup nutzt KI als erg\u00e4nzende Technologie und nicht als zentralen oder integralen Bestandteil.<br \/>Beispiel: Ein Projektmanagement-Startup, das KI verwendet, um interne Prozesse effizienter zu gestalten.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1429\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1429\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">ICH HABE KEIN TEAM. KANN ICH TROTZDEM AM PROGRAMM TEILNEHMEN?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1429\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1429\"><p>In der Regel bestehen die erfolgreichsten Startups aus mindestens zwei Mitbegr\u00fcndern, die die technischen und gesch\u00e4ftlichen Grundlagen abdecken k\u00f6nnen. Wenn Sie ein au\u00dfergew\u00f6hnliches Talent sind und glauben, dass Sie das Zeug dazu haben, Ihr eigenes Unternehmen zu gr\u00fcnden, k\u00f6nnen wir eine Ausnahme machen. Au\u00dferdem k\u00f6nnten wir Sie m\u00f6glicherweise mit einem geeigneten Mitbegr\u00fcnder zusammenbringen. Melden Sie sich und schauen wir, ob wir Ihnen helfen k\u00f6nnen.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-14210\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-14210\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">ICH HABE EINEN VOLLZEITJOB ODER ICH STUDIERE. IST IHR PROGRAMM F\u00dcR MICH GEEIGNET?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-14210\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-14210\"><p>Was wir von unseren Teilnehmern erwarten, ist volles Engagement, um an allen Workshops teilzunehmen. Daneben m\u00fcssen Sie an Ihrem Projekt arbeiten, jedoch in flexiblem Stil. Schauen Sie sich den Zeitplan f\u00fcr weitere Details an.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-14211\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-14211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">IN WELCHEM STADIUM SOLLTE MEINE IDEE ODER MEIN STARTUP SEIN, UM AM PROGRAMM TEILZUNEHMEN?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-14211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-14211\"><p>Unser Programm richtet sich an unerfahrene Gr\u00fcnder und Fr\u00fchphasen-Startups mit einer Idee oder einem Projekt im Bereich KI. Sie k\u00f6nnen als Einzelperson, Team oder auch als Startup mit einer Einheit teilnehmen.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-14212\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-14212\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">MUSS ICH F\u00dcR DIE DAUER DES PROGRAMMS IN HEILBRONN SEIN?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-14212\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-14212\"><p>Um das Beste aus dem Programm herauszuholen, wird eine physische Teilnahme w\u00e4hrend des Programms dringend bevorzugt. Die Teilnahme an den Workshops ist verpflichtend. An anderen Tagen k\u00f6nnen Sie unseren Raum nutzen oder dort arbeiten, wo Sie m\u00f6chten.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-14213\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-14213\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">ICH HABE EINE ANDERE FRAGE ZUM BEWERBUNGSPROZESS ODER ZUM PROGRAMM. WO BEKOMME ICH HILFE?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-14213\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-14213\"><p>Wir werden vor dem Start des Durchgangs mehrere Fragerunden durchf\u00fchren. Sie k\u00f6nnen uns dort beitreten, um Ihre Fragen beantwortet zu bekommen. Beachten Sie unsere bevorstehenden Veranstaltungen. Alternativ k\u00f6nnen Sie sich an Benni@campusfounders.de wenden, um Hilfe zu erhalten.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-53d78f6 elementor-section-height-min-height cf-section cf-closing elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"53d78f6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f3c6dd\" data-id=\"3f3c6dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-65e8001 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65e8001\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1c69ae8\" data-id=\"1c69ae8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfdfcb4 elementor-widget elementor-widget-heading\" data-id=\"dfdfcb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bist du bereit f\u00fcr Deine <span class='text-wattle'><b>ersten unternehmerischen<\/b><\/span> Schritte? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-511f012 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"511f012\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a1a5365\" data-id=\"a1a5365\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b1427b elementor-align-right elementor-laptop-align-right elementor-mobile-align-left elementor-widget-laptop__width-auto sbtn btn-manatedark elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"5b1427b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/campusfounders.typeform.com\/to\/MeaTvM54\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Warteliste<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-053e757 cf-section partner-logos elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"053e757\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24fa3e1f\" data-id=\"24fa3e1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a462683 elementor-widget elementor-widget-title-subtitle\" data-id=\"a462683\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class='cf-git'>\n            <div class='git-title' style='opacity: 1'><\/div>\n            <div class='git-seperator' style='height: 2px'><\/div>\n            <div class='git-name'>PARTNER <b class=\"git-lastname\"><\/b><\/div>\n            <div class='git-greeting' style='opacity: 1'>\n                \n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-7eef221c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eef221c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-252c341\" data-id=\"252c341\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79e4e2d2 elementor-widget elementor-widget-image\" data-id=\"79e4e2d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2024\/07\/innoWerft-logo-black.svg\" class=\"attachment-medium size-medium wp-image-29455\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6dd51c39\" data-id=\"6dd51c39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4259e7d8 elementor-widget elementor-widget-image\" data-id=\"4259e7d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2025\/01\/partner-ipai-new.svg\" class=\"attachment-medium size-medium wp-image-30269\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-40e83f5d\" data-id=\"40e83f5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3de1a71 elementor-widget elementor-widget-image\" data-id=\"3de1a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/12\/partner_startupBW_Logo.svg\" class=\"attachment-medium size-medium wp-image-26233\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-110403\" data-id=\"110403\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21b672c1 elementor-widget elementor-widget-image\" data-id=\"21b672c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2023\/12\/partner_TUMVentureLabAI_Logo2.svg\" class=\"attachment-medium size-medium wp-image-26237\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Programm\u00fcbersicht Zeitleiste Team FAQ AI START Starte deine KI-Gesch\u00e4ftsidee in nur 4 Wochen durch. Warteliste Wo angehende Gr\u00fcnder*innen modernste KI mit strategischem Gesch\u00e4ftssinn verbinden, um transformative Startups aufzubauen. Programm\u00fcbersicht \u201eAI Start\u201c ist der Beginn Deiner Reise als KI-Startup-Gr\u00fcnder\/in. Der Kurs erm\u00f6glicht es Dir in nur vier Wochen Deine Startup-Idee durch die Entwicklung von KI-basierten Prototypen [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":13081,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-26116","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AI Start - Campus Founders<\/title>\n<meta name=\"description\" content=\"\u201eAI Start\u201c ist der Beginn Deiner Reise als KI-Startup-Gr\u00fcnder\/in. Der Kurs erm\u00f6glicht es dir in nur vier Wochen Deine Startup-Idee durch die Entwicklung von KI-basierten Prototypen weiter zu entwickeln und zu validieren. Das Programm bringt Dir wesentliche Gesch\u00e4ftskomponenten n\u00e4her, wie Teambildung, Problemidentifizierung, Value Proposition, Pitching, MVP-Entwicklung, Grundlagen zu Gesch\u00e4ftsmodellen, Kapitalbeschaffung und rechtlichen \u00dcberlegungen. Dar\u00fcber hinaus bietet er spezielle Inhalte zu KI, einschlie\u00dflich deren Anwendung, Automatisierung, personalisierte KI-Modelle, Prototyping, Produktentwicklung und KI-getriebener Gesch\u00e4ftsmodelle. Die Teilnahme am Programm ist kostenlos, erfordert jedoch eine Bewerbung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusfounders.de\/de\/talent\/ai-start\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AI Start - Campus Founders\" \/>\n<meta property=\"og:description\" content=\"\u201eAI Start\u201c ist der Beginn Deiner Reise als KI-Startup-Gr\u00fcnder\/in. Der Kurs erm\u00f6glicht es dir in nur vier Wochen Deine Startup-Idee durch die Entwicklung von KI-basierten Prototypen weiter zu entwickeln und zu validieren. Das Programm bringt Dir wesentliche Gesch\u00e4ftskomponenten n\u00e4her, wie Teambildung, Problemidentifizierung, Value Proposition, Pitching, MVP-Entwicklung, Grundlagen zu Gesch\u00e4ftsmodellen, Kapitalbeschaffung und rechtlichen \u00dcberlegungen. Dar\u00fcber hinaus bietet er spezielle Inhalte zu KI, einschlie\u00dflich deren Anwendung, Automatisierung, personalisierte KI-Modelle, Prototyping, Produktentwicklung und KI-getriebener Gesch\u00e4ftsmodelle. Die Teilnahme am Programm ist kostenlos, erfordert jedoch eine Bewerbung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusfounders.de\/de\/talent\/ai-start\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Founders\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T13:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2022\/08\/CCC_4K_Visual_V2-1-1024x576.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/campusfounders.de\/wp-content\/uploads\/2022\/08\/CCC_4K_Visual_V2-1-1024x576.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/ai-start\\\/\",\"url\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/ai-start\\\/\",\"name\":\"AI Start - Campus Founders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/ai-start\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/ai-start\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.facebook.com\\\/tr?id=2079266535932983&ev=PageView&noscript=1\",\"datePublished\":\"2023-12-04T12:57:23+00:00\",\"dateModified\":\"2026-05-04T13:43:05+00:00\",\"description\":\"\u201eAI Start\u201c ist der Beginn Deiner Reise als KI-Startup-Gr\u00fcnder\\\/in. Der Kurs erm\u00f6glicht es dir in nur vier Wochen Deine Startup-Idee durch die Entwicklung von KI-basierten Prototypen weiter zu entwickeln und zu validieren. Das Programm bringt Dir wesentliche Gesch\u00e4ftskomponenten n\u00e4her, wie Teambildung, Problemidentifizierung, Value Proposition, Pitching, MVP-Entwicklung, Grundlagen zu Gesch\u00e4ftsmodellen, Kapitalbeschaffung und rechtlichen \u00dcberlegungen. Dar\u00fcber hinaus bietet er spezielle Inhalte zu KI, einschlie\u00dflich deren Anwendung, Automatisierung, personalisierte KI-Modelle, Prototyping, Produktentwicklung und KI-getriebener Gesch\u00e4ftsmodelle. Die Teilnahme am Programm ist kostenlos, erfordert jedoch eine Bewerbung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/ai-start\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/ai-start\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/ai-start\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.facebook.com\\\/tr?id=2079266535932983&ev=PageView&noscript=1\",\"contentUrl\":\"https:\\\/\\\/www.facebook.com\\\/tr?id=2079266535932983&ev=PageView&noscript=1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/ai-start\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Talent\",\"item\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/talent\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AI Start\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/\",\"name\":\"Campus Founders\",\"description\":\"Home Of Entrepreneurs &amp; Innovators\",\"publisher\":{\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/#organization\",\"name\":\"Campus Founders\",\"url\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/campusfounders.de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-CMYK-Original.svg\",\"contentUrl\":\"https:\\\/\\\/campusfounders.de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-CMYK-Original.svg\",\"width\":1591,\"height\":247,\"caption\":\"Campus Founders\"},\"image\":{\"@id\":\"https:\\\/\\\/campusfounders.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AI Start - Campus Founders","description":"\u201eAI Start\u201c ist der Beginn Deiner Reise als KI-Startup-Gr\u00fcnder\/in. Der Kurs erm\u00f6glicht es dir in nur vier Wochen Deine Startup-Idee durch die Entwicklung von KI-basierten Prototypen weiter zu entwickeln und zu validieren. Das Programm bringt Dir wesentliche Gesch\u00e4ftskomponenten n\u00e4her, wie Teambildung, Problemidentifizierung, Value Proposition, Pitching, MVP-Entwicklung, Grundlagen zu Gesch\u00e4ftsmodellen, Kapitalbeschaffung und rechtlichen \u00dcberlegungen. Dar\u00fcber hinaus bietet er spezielle Inhalte zu KI, einschlie\u00dflich deren Anwendung, Automatisierung, personalisierte KI-Modelle, Prototyping, Produktentwicklung und KI-getriebener Gesch\u00e4ftsmodelle. Die Teilnahme am Programm ist kostenlos, erfordert jedoch eine Bewerbung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/","og_locale":"de_DE","og_type":"article","og_title":"AI Start - Campus Founders","og_description":"\u201eAI Start\u201c ist der Beginn Deiner Reise als KI-Startup-Gr\u00fcnder\/in. Der Kurs erm\u00f6glicht es dir in nur vier Wochen Deine Startup-Idee durch die Entwicklung von KI-basierten Prototypen weiter zu entwickeln und zu validieren. Das Programm bringt Dir wesentliche Gesch\u00e4ftskomponenten n\u00e4her, wie Teambildung, Problemidentifizierung, Value Proposition, Pitching, MVP-Entwicklung, Grundlagen zu Gesch\u00e4ftsmodellen, Kapitalbeschaffung und rechtlichen \u00dcberlegungen. Dar\u00fcber hinaus bietet er spezielle Inhalte zu KI, einschlie\u00dflich deren Anwendung, Automatisierung, personalisierte KI-Modelle, Prototyping, Produktentwicklung und KI-getriebener Gesch\u00e4ftsmodelle. Die Teilnahme am Programm ist kostenlos, erfordert jedoch eine Bewerbung.","og_url":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/","og_site_name":"Campus Founders","article_modified_time":"2026-05-04T13:43:05+00:00","og_image":[{"url":"https:\/\/campusfounders.de\/wp-content\/uploads\/2022\/08\/CCC_4K_Visual_V2-1-1024x576.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/campusfounders.de\/wp-content\/uploads\/2022\/08\/CCC_4K_Visual_V2-1-1024x576.jpg","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/","url":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/","name":"AI Start - Campus Founders","isPartOf":{"@id":"https:\/\/campusfounders.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/#primaryimage"},"image":{"@id":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/#primaryimage"},"thumbnailUrl":"https:\/\/www.facebook.com\/tr?id=2079266535932983&ev=PageView&noscript=1","datePublished":"2023-12-04T12:57:23+00:00","dateModified":"2026-05-04T13:43:05+00:00","description":"\u201eAI Start\u201c ist der Beginn Deiner Reise als KI-Startup-Gr\u00fcnder\/in. Der Kurs erm\u00f6glicht es dir in nur vier Wochen Deine Startup-Idee durch die Entwicklung von KI-basierten Prototypen weiter zu entwickeln und zu validieren. Das Programm bringt Dir wesentliche Gesch\u00e4ftskomponenten n\u00e4her, wie Teambildung, Problemidentifizierung, Value Proposition, Pitching, MVP-Entwicklung, Grundlagen zu Gesch\u00e4ftsmodellen, Kapitalbeschaffung und rechtlichen \u00dcberlegungen. Dar\u00fcber hinaus bietet er spezielle Inhalte zu KI, einschlie\u00dflich deren Anwendung, Automatisierung, personalisierte KI-Modelle, Prototyping, Produktentwicklung und KI-getriebener Gesch\u00e4ftsmodelle. Die Teilnahme am Programm ist kostenlos, erfordert jedoch eine Bewerbung.","breadcrumb":{"@id":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusfounders.de\/de\/talent\/ai-start\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/#primaryimage","url":"https:\/\/www.facebook.com\/tr?id=2079266535932983&ev=PageView&noscript=1","contentUrl":"https:\/\/www.facebook.com\/tr?id=2079266535932983&ev=PageView&noscript=1"},{"@type":"BreadcrumbList","@id":"https:\/\/campusfounders.de\/de\/talent\/ai-start\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Talent","item":"https:\/\/campusfounders.de\/de\/talent\/"},{"@type":"ListItem","position":2,"name":"AI Start"}]},{"@type":"WebSite","@id":"https:\/\/campusfounders.de\/de\/#website","url":"https:\/\/campusfounders.de\/de\/","name":"Campus Founders","description":"Home Of Entrepreneurs &amp; Innovators","publisher":{"@id":"https:\/\/campusfounders.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusfounders.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/campusfounders.de\/de\/#organization","name":"Campus Founders","url":"https:\/\/campusfounders.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/campusfounders.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/campusfounders.de\/wp-content\/uploads\/2021\/09\/Logo-CMYK-Original.svg","contentUrl":"https:\/\/campusfounders.de\/wp-content\/uploads\/2021\/09\/Logo-CMYK-Original.svg","width":1591,"height":247,"caption":"Campus Founders"},"image":{"@id":"https:\/\/campusfounders.de\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/pages\/26116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/comments?post=26116"}],"version-history":[{"count":82,"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/pages\/26116\/revisions"}],"predecessor-version":[{"id":31888,"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/pages\/26116\/revisions\/31888"}],"up":[{"embeddable":true,"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/pages\/13081"}],"wp:attachment":[{"href":"https:\/\/campusfounders.de\/de\/wp-json\/wp\/v2\/media?parent=26116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}